{"id":276931,"date":"2025-03-04T08:43:46","date_gmt":"2025-03-04T07:43:46","guid":{"rendered":"https:\/\/lasellatimes.com\/?page_id=276931"},"modified":"2025-10-05T09:11:20","modified_gmt":"2025-10-05T07:11:20","slug":"lst-bands-performers","status":"publish","type":"page","link":"https:\/\/lasellatimes.com\/es\/lst-bands-performers\/","title":{"rendered":"LST Bands &#038; Performers"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"276931\" class=\"elementor elementor-276931\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div data-dce-background-overlay-color=\"#000000\" data-dce-background-image-url=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg\" class=\"elementor-element elementor-element-5f6c97c3 e-flex e-con-boxed e-con e-parent\" data-id=\"5f6c97c3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div data-dce-title-color=\"#FFFBFB\" class=\"elementor-element elementor-element-67250dba elementor-widget elementor-widget-heading\" data-id=\"67250dba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>LST WORD<br><br>Bands And Musicians<br><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-text-color=\"#FFFFFF\" class=\"elementor-element elementor-element-18b33e2c elementor-widget elementor-widget-text-editor\" data-id=\"18b33e2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Discover the Best Bands And Musicians in and Around Denia<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40ae9b5 e-flex e-con-boxed e-con e-parent\" data-id=\"40ae9b5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ec5f18 elementor-widget elementor-widget-heading\" data-id=\"9ec5f18\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Selection Of The Best Bands &amp; Musicians <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21255299 elementor-widget elementor-widget-smartmag-grid\" data-id=\"21255299\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"smartmag-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section class=\"block-wrap block-grid block-sc\" data-id=\"1\">\n\n\t\t\t\t\n\t\t\t<div class=\"block-content\">\n\t\t\t\t\t\n\t<div class=\"loop loop-grid loop-grid-base grid grid-4 md:grid-3 sm:grid-2\">\n\n\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/3-musicteers\/\" class=\"image-link media-ratio ratio-4-3\" title=\"3 MusicTeers\"><img fetchpriority=\"high\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"3 MusicTeers\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/3mteers.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/3-musicteers\/\">3 MusicTeers<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>What do a former bank manager, a sales rep and a web\/graphic designer have in common? A passion for music! Everyone has their own experiences: Dani was a member of&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/adam-daniels\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Adam Daniels\"><img decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Adam Daniels\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/AdamDaniels.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/adam-daniels\/\">Adam Daniels<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Adam is a solo singer,guitarist and pianist who entertains with live music all over the Costa Blanca.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/black-glitter-lady-k-and-the-jjs\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Black Glitter\"><img decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Black Glitter\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/10\/Black-Glitter.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/black-glitter-lady-k-and-the-jjs\/\">Black Glitter<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Cover band of classics from the 70s and 80s. performing Classics by Tina Turner, Donna Summers, Etta James, Jannis Joplin, Aretha Franklin, Steve Wonder plus contemporary Rock, Soul and Disco.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/chill-factor\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Chill Factor\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Chill Factor\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/ChillFactor.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/chill-factor\/\">Chill Factor<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Enjoy songs by artists including The Police, Fleetwood Mac, Santana, U2, Ben Howard, Hozier, Chris Rea, Empire of the Sun, Oasis, Dire Straits, Crowded House, Pretenders, Pink Floyd, The Beatles etc.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/don-dimo-y-gali\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Don Dimo ( y Gali)\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Don Dimo ( y Gali)\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DonDimoGaly.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/don-dimo-y-gali\/\">Don Dimo ( y Gali)<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Don Dimo plays and improvises all styles of music including Blues, Rock, Pop, Flamenco, Spanish and more.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/eliezer\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Eliezer\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Eliezer\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/eli2.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/eliezer\/\">Eliezer<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Multi-talented singer \/ musician from the Dominican Republic. From Bachata (like Cuban salsa but better) to Bocelli.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/esencia-flamenca\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Esencia Flamenca\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"EsenciaFlamenca\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Esencia Flamenca\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/3.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/esencia-flamenca\/\">Esencia Flamenca<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Esencias music ranges from Pure Flamenco to Flamenquito Fusion, Jazz, Nossa Nova, Funk, and Arabic.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/golden-era-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Golden Era Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Golden Era Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/10\/tapas-dance.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/golden-era-band\/\">Golden Era Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>A new band for a mid weekly dinner dance events.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/inti-cardoso\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Inti Cardoso.\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Inti Cardoso.\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/inti.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/inti-cardoso\/\">Inti Cardoso.<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Accomplished Cuban guitarist playing and singing all genres of music from the classics to Hard Rock.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/kennys-cabaret-of-music\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Kenny&#8217;s Cabaret Of Music\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Kenny&#8217;s Cabaret Of Music\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/09\/kenny.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/kennys-cabaret-of-music\/\">Kenny&#8217;s Cabaret Of Music<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Ahora residente en Espa\u00f1a y disfrutando interpretando tributos y todos los g\u00e9neros de todos los a\u00f1os, \u00a1simplemente pas\u00e1ndolo en grande!<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/kirsty-dewar\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Kirsty Dewar\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Kirsty Dewar\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/08\/k3.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/kirsty-dewar\/\">Kirsty Dewar<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Kirsty is a multi instrumentalist, playing Acoustic Guitar, Piano, Cello and Ukulele.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/la-mocha\/\" class=\"image-link media-ratio ratio-4-3\" title=\"La Mocha\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"La Mocha\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Mocha3.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/la-mocha\/\">La Mocha<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Originally from Argentina, La Mocha have been playing Rock &amp; Roll in Spain for almost 20 years. Comprising Ariel, Mauro, Adri\u00e1n and Jose Manuel Mas and Diego Baez, 4 brothers&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/mariano-fugillo\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Mariano Fugillo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Mariano Fugillo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Fugillo.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/mariano-fugillo\/\">Mariano Fugillo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Mariano Fugillo is an Argentine musician and subject of the biographical documentary film\u00a0&#8220;Hits en otra Dimensi\u00f3n&#8221;.\u00a0<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/matt-curtis-mason\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Matt Curtis Mason\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Matt Curtis Mason\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Matt1-2.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/matt-curtis-mason\/\">Matt Curtis Mason<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>The Entertainer Professional Vocalist &amp; Entertainer popular for parties, weddings, clubs and bars.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/moonshine-duo\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Moonshine Duo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"moonshine3\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Moonshine Duo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/Moonshine-1024-image3.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/moonshine-duo\/\">Moonshine Duo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\t\t\t\n\t\t\t\t<div class=\"excerpt\">\n\t\t\t\t\t<p>Vic and Chloe bring you songs we all know and love with a sprinkle of Moonshine acoustic sparkle.<\/p>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\n\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00a4a72 elementor-widget elementor-widget-smartmag-grid\" data-id=\"00a4a72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"smartmag-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<section class=\"block-wrap block-grid block-sc\" data-id=\"2\">\n\n\t\t\t\t\n\t\t\t<div class=\"block-content\">\n\t\t\t\t\t\n\t<div class=\"loop loop-grid loop-grid-base grid grid-5 md:grid-3 sm:grid-2\">\n\n\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/20-20-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Banda 20\/20\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Banda 20\/20\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/2020arena1000.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/20-20-band\/\">Banda 20\/20<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/amy-winehouse-tribute\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Homenaje a Amy Winehouse\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Homenaje a Amy Winehouse\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AmyWinehouseEMM.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/amy-winehouse-tribute\/\">Homenaje a Amy Winehouse<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/andy-cheeky-blinder\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Andy \/ Cheeky Blinder\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Andy \/ Cheeky Blinder\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/AndyFenwick.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/andy-cheeky-blinder\/\">Andy \/ Cheeky Blinder<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/angel-station\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Angel Station\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Angel Station\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/AngelStation.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/angel-station\/\">Angel Station<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/becky-bb\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Becky BB\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Becky BB\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BeckyBB.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/becky-bb\/\">Becky BB<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/black-velvet\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Black Velvet\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Black Velvet\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/BlackVelvet.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/black-velvet\/\">Black Velvet<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/brink-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Brink Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Brink Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/BrinkBand.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/brink-band\/\">Brink Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/culture-shock\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Choque cultural\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Choque cultural\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Cultureshockduo.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/culture-shock\/\">Choque cultural<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/dave-manhattan\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Dave Manhattan\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/davemanhattan-450x514.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Dave Manhattan\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/davemanhattan-450x514.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/davemanhattan-263x300.jpg 263w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/davemanhattan.jpg 652w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/dave-manhattan\/\">Dave Manhattan<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/david-bellingham\/\" class=\"image-link media-ratio ratio-4-3\" title=\"David Bellingham\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DaveBellingham-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"David Bellingham\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DaveBellingham-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DaveBellingham-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DaveBellingham-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DaveBellingham.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/david-bellingham\/\">David Bellingham<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/dc3\/\" class=\"image-link media-ratio ratio-4-3\" title=\"DC3\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DC3Rock-1-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"DC3\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DC3Rock-1-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DC3Rock-1-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DC3Rock-1-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DC3Rock-1.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/dc3\/\">DC3<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/el-legendario-doctor-ron\/\" class=\"image-link media-ratio ratio-4-3\" title=\"El Legendario Doctor Ron\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DoctorRon-1-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"El Legendario Doctor Ron\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DoctorRon-1-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DoctorRon-1-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DoctorRon-1-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/DoctorRon-1.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/el-legendario-doctor-ron\/\">El Legendario Doctor Ron<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/embrujo-flamenco\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Embrujo Flamenco\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-450x337.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Embrujo Flamenco\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-450x337.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-300x224.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-1024x766.jpg 1024w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-768x575.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-200x150.jpg 200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-150x112.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo-1200x898.jpg 1200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/embrujo.jpg 1290w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/embrujo-flamenco\/\">Embrujo Flamenco<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/gatecrash\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Gatecrash\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Gatecrash\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Gatecrash.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/gatecrash\/\">Gatecrash<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/ian-hunt\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Ian Hunt\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Ian-Hunt-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Ian Hunt\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Ian-Hunt-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Ian-Hunt-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Ian-Hunt-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Ian-Hunt.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/ian-hunt\/\">Ian Hunt<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/irish-des\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Irish Des\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/IrishDes1-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Irish Des\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/IrishDes1-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/IrishDes1-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/IrishDes1-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/IrishDes1.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/irish-des\/\">Irish Des<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jai-larkan\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Jai Larkan\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Jai Larkan\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JaiLarkan.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jai-larkan\/\">Jai Larkan<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/james-hurst\/\" class=\"image-link media-ratio ratio-4-3\" title=\"James Hurst\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JamesHurst-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"James Hurst\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JamesHurst-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JamesHurst-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JamesHurst-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JamesHurst.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/james-hurst\/\">James Hurst<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/janette-deb\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Janette &#038; Deb\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Janette_Deb_AngelStation-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Janette &#038; Deb\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Janette_Deb_AngelStation-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Janette_Deb_AngelStation-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Janette_Deb_AngelStation-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Janette_Deb_AngelStation.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/janette-deb\/\">Janette &#038; Deb<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jim-shearer\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Jim Shearer\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JimShearer-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Jim Shearer\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JimShearer-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JimShearer-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JimShearer-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JimShearer.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jim-shearer\/\">Jim Shearer<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jj-jones-neil-diamond-tribute\/\" class=\"image-link media-ratio ratio-4-3\" title=\"JJ Jones- Tributo a Neil Diamond\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"JJ Jones- Tributo a Neil Diamond\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/NeilDiamondTributeJJ.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/jj-jones-neil-diamond-tribute\/\">JJ Jones- Tributo a Neil Diamond<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/joe-wilkinson\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Joe Wilkinson\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JoeWilkinson-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Joe Wilkinson\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JoeWilkinson-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JoeWilkinson-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JoeWilkinson-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JoeWilkinson.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/joe-wilkinson\/\">Joe Wilkinson<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juan-acevedo\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Juan Acevedo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JuanAcevedo-450x600.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Juan Acevedo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JuanAcevedo-450x600.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JuanAcevedo-225x300.jpg 225w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JuanAcevedo-300x400.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/JuanAcevedo.jpg 768w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juan-acevedo\/\">Juan Acevedo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juan-saez\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Juan S\u00e1ez\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JuanSaez-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Juan S\u00e1ez\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JuanSaez-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JuanSaez-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JuanSaez-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/JuanSaez.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juan-saez\/\">Juan S\u00e1ez<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juntos-revueltos\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Juntos Revueltos\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Juntos Revueltos\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Juntosrevueltos.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/juntos-revueltos\/\">Juntos Revueltos<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/knot-again\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Nudo de nuevo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/KnotAgain2-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Nudo de nuevo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/KnotAgain2-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/KnotAgain2-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/KnotAgain2-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/KnotAgain2.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/knot-again\/\">Nudo de nuevo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/la-banda-de-la-abuela\/\" class=\"image-link media-ratio ratio-4-3\" title=\"La Banda De La Abuela\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"La Banda De La Abuela\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/laBandaDeLaAbuela1000.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/la-banda-de-la-abuela\/\">La Banda De La Abuela<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lady-jazz\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Lady Jazz\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Lady Jazz\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LadyJazz.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lady-jazz\/\">Lady Jazz<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lady-k-and-the-jjs\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Lady K and the JJ\u2019s\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/ladykjjs-450x203.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Lady K and the JJ\u2019s\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/ladykjjs-1024x461.jpg 1024w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/ladykjjs-768x346.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/ladykjjs.jpg 1080w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lady-k-and-the-jjs\/\">Lady K and the JJ\u2019s<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/larry-mcconville\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Larry McConville\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Larry McConville\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LarryMcconville.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/larry-mcconville\/\">Larry McConville<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/laurence-archer\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Laurence Archer\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Laurence Archer\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-200x150.jpg 200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/03\/larcher.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/laurence-archer\/\">Laurence Archer<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lol-i-pop\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Lol i Pop\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LoliPop-450x600.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Lol i Pop\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LoliPop-450x600.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LoliPop-225x300.jpg 225w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LoliPop.jpg 768w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/lol-i-pop\/\">Lol i Pop<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/los-legendarios\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Los Legendarios\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Los Legendarios\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/LosLegendarios.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/los-legendarios\/\">Los Legendarios<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/los-musiqueros-de-los-jueves\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Los Musiqueros De Los Jueves\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/losmusiqueros-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Los Musiqueros De Los Jueves\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/losmusiqueros-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/losmusiqueros-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/losmusiqueros-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/losmusiqueros.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/los-musiqueros-de-los-jueves\/\">Los Musiqueros De Los Jueves<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/marise-fox\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Marise Fox\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MariseFox-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Marise Fox\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MariseFox-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MariseFox-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MariseFox-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MariseFox.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/marise-fox\/\">Marise Fox<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/mclucas\/\" class=\"image-link media-ratio ratio-4-3\" title=\"McLucas\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"McLucas\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/McLucas.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/mclucas\/\">McLucas<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/montgo-music\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Montgo Music\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Montgo Music\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/MontgoMusic.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/montgo-music\/\">Montgo Music<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/multipass\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Multipass\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Multipass\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/Multipass.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/multipass\/\">Multipass<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/nestor-paz\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Nestor &#038; Paz\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/paznestor-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Nestor &#038; Paz\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/paznestor-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/paznestor-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/paznestor-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/paznestor.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/nestor-paz\/\">Nestor &#038; Paz<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/paul-valen\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Paul &#038; Valen\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Paul &#038; Valen\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/PaulyValen.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/paul-valen\/\">Paul &#038; Valen<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/rafa-raposo\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Rafa Raposo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Rafa Raposo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/RafaRaposo.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/rafa-raposo\/\">Rafa Raposo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/renegades\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Renegades\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Renegades-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Renegades\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Renegades-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Renegades-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Renegades-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Renegades.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/renegades\/\">Renegades<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/rio\/\" class=\"image-link media-ratio ratio-4-3\" title=\"R\u00edo\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"R\u00edo\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-200x150.jpg 200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/02\/Rio.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/rio\/\">R\u00edo<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/slide-boy-vegas\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Slide Boy Vegas\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Slide Boy Vegas\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SlideboyVegas.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/slide-boy-vegas\/\">Slide Boy Vegas<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/strikland\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Strikland\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Strikland-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Strikland\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Strikland-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Strikland-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Strikland-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/Strikland.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/strikland\/\">Strikland<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/sugar-shack\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Sugar Shack\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SugarShack-450x600.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Sugar Shack\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SugarShack-450x600.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SugarShack-225x300.jpg 225w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SugarShack-300x400.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/SugarShack.jpg 768w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/sugar-shack\/\">Sugar Shack<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/suite-rumba\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Suite Rumba\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/SuiteRumba-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Suite Rumba\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/SuiteRumba-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/SuiteRumba-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/SuiteRumba-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/SuiteRumba.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/suite-rumba\/\">Suite Rumba<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/tamy-the-sweet-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Tamy &#038; The Sweet Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Tamy &#038; The Sweet Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TamySweetBand.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/tamy-the-sweet-band\/\">Tamy &#038; The Sweet Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/tender-caves\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Tender Caves\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Tender Caves\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/TenderCaves.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/tender-caves\/\">Tender Caves<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-cap-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"The Cap Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/TheCapBand-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"The Cap Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/TheCapBand-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/TheCapBand-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/TheCapBand-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/TheCapBand.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-cap-band\/\">The Cap Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-new-jubilee-jazz-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"La New Jubilee Jazz Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"LST Musica En Vivo En Denia Javea Moraira Y Jalon\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"La New Jubilee Jazz Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2023\/03\/NewJubilee.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-new-jubilee-jazz-band\/\">La New Jubilee Jazz Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-ok-band\/\" class=\"image-link media-ratio ratio-4-3\" title=\"The OK Band\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-450x416.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"The OK Band\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-450x416.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-300x278.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-1024x947.jpg 1024w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-768x711.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo-1200x1110.jpg 1200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/OKBandLogo.jpg 1338w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-ok-band\/\">The OK Band<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-view\/\" class=\"image-link media-ratio ratio-4-3\" title=\"The View\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb-450x450.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"The View\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb-450x450.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb-300x300.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb-768x768.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb-500x500.jpg 500w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/AndyDeb.jpg 1000w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/the-view\/\">The View<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\t\t\t\n<article class=\"l-post grid-post grid-base-post l-post-center\">\n\n\t\n\t\t\t<div class=\"media\">\n\n\t\t\n\t\t\t<a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/yumi-y-arley\/\" class=\"image-link media-ratio ratio-4-3\" title=\"Yumi y Arley\"><img loading=\"lazy\" decoding=\"async\" width=\"368\" height=\"276\" src=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-450x338.jpg\" class=\"attachment-bunyad-medium size-bunyad-medium wp-post-image\" alt=\"\" sizes=\"(max-width: 368px) 100vw, 368px\" title=\"Yumi y Arley\" srcset=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-450x338.jpg 450w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-300x225.jpg 300w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-768x576.jpg 768w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-16x12.jpg 16w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-200x150.jpg 200w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024-150x113.jpg 150w, https:\/\/lasellatimes.com\/wp-content\/uploads\/2025\/03\/yumi-y-arley1024.jpg 1024w\" \/><\/a>\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\n\t\t<\/div>\n\t\n\n\t\n\t\t<div class=\"content\">\n\n\t\t\t<div class=\"post-meta post-meta-a\"><h2 class=\"is-title post-title\"><a href=\"https:\/\/lasellatimes.com\/es\/lstartists\/yumi-y-arley\/\">Yumi y Arley<\/a><\/h2><\/div>\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\n\t\n<\/article>\t\t\n\t<\/div>\n\n\t\t\n\t\t\t<\/div>\n\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c05432 elementor-share-buttons--view-icon-text elementor-share-buttons--skin-gradient elementor-share-buttons--shape-square elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"6c05432\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tFacebook\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tTwitter\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-share-btn__text\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__title\">\n\t\t\t\t\t\t\t\t\t\tLinkedIn\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f739c41 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7f739c41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lasellatimes.com\/es\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Volver a la p\u00e1gina de inicio<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>LST WORD Bands And Musicians Discover the Best Bands And Musicians in and Around Denia Selection Of The Best Bands &amp; Musicians 3 MusicTeers What do a former bank manager, a sales rep and a web\/graphic designer have in common? A passion for music! Everyone has their own experiences: Dani was a member of&hellip; Adam<\/p>","protected":false},"author":2,"featured_media":269990,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/blocks.php","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[337,336],"tags":[],"class_list":{"0":"post-276931","1":"page","2":"type-page","3":"status-publish","4":"has-post-thumbnail","6":"category-artists","7":"category-featured-artists"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Best Bands And Musicians In And Around Denia<\/title>\n<meta name=\"description\" content=\"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lasellatimes.com\/es\/lst-bands-performers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Best Restaurants Around Denia\" \/>\n<meta property=\"og:description\" content=\"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasellatimes.com\/es\/lst-bands-performers\/\" \/>\n<meta property=\"og:site_name\" content=\"lasellatimes.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-05T07:11:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"613\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/\",\"name\":\"The Best Bands And Musicians In And Around Denia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/LSThomepagemusicbanner.jpg\",\"datePublished\":\"2025-03-04T07:43:46+00:00\",\"dateModified\":\"2025-10-05T07:11:20+00:00\",\"description\":\"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/LSThomepagemusicbanner.jpg\",\"contentUrl\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/LSThomepagemusicbanner.jpg\",\"width\":1600,\"height\":613},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/lst-bands-performers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lasellatimes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LST Bands &#038; Performers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#website\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/\",\"name\":\"lasellatimes.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasellatimes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#organization\",\"name\":\"lasellatimes.com\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"lasellatimes.com\"},\"image\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Best Bands And Musicians In And Around Denia","description":"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lasellatimes.com\/es\/lst-bands-performers\/","og_locale":"es_ES","og_type":"article","og_title":"Best Restaurants Around Denia","og_description":"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes","og_url":"https:\/\/lasellatimes.com\/es\/lst-bands-performers\/","og_site_name":"lasellatimes.com","article_modified_time":"2025-10-05T07:11:20+00:00","og_image":[{"width":1600,"height":613,"url":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/","url":"https:\/\/lasellatimes.com\/lst-bands-performers\/","name":"The Best Bands And Musicians In And Around Denia","isPartOf":{"@id":"https:\/\/lasellatimes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/#primaryimage"},"image":{"@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/#primaryimage"},"thumbnailUrl":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg","datePublished":"2025-03-04T07:43:46+00:00","dateModified":"2025-10-05T07:11:20+00:00","description":"A Selection Of The Best Bands And Musicians In And around Denia And Les Marines in Spains North Costa Blanca From Desveses To Les Rotes","breadcrumb":{"@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasellatimes.com\/lst-bands-performers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/#primaryimage","url":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg","contentUrl":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2024\/12\/LSThomepagemusicbanner.jpg","width":1600,"height":613},{"@type":"BreadcrumbList","@id":"https:\/\/lasellatimes.com\/lst-bands-performers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lasellatimes.com\/"},{"@type":"ListItem","position":2,"name":"LST Bands &#038; Performers"}]},{"@type":"WebSite","@id":"https:\/\/lasellatimes.com\/#website","url":"https:\/\/lasellatimes.com\/","name":"lasellatimes.com","description":"","publisher":{"@id":"https:\/\/lasellatimes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasellatimes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lasellatimes.com\/#organization","name":"lasellatimes.com","url":"https:\/\/lasellatimes.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lasellatimes.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"lasellatimes.com"},"image":{"@id":"https:\/\/lasellatimes.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/pages\/276931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/comments?post=276931"}],"version-history":[{"count":9,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/pages\/276931\/revisions"}],"predecessor-version":[{"id":280814,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/pages\/276931\/revisions\/280814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/media\/269990"}],"wp:attachment":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/media?parent=276931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/categories?post=276931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/tags?post=276931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}