{"id":280702,"date":"2025-09-25T14:32:39","date_gmt":"2025-09-25T12:32:39","guid":{"rendered":"https:\/\/lasellatimes.com\/?post_type=mec-events&#038;p=280702"},"modified":"2026-05-03T11:05:57","modified_gmt":"2026-05-03T09:05:57","slug":"oisin-valen-at-beni-ruta-66","status":"publish","type":"mec-events","link":"https:\/\/lasellatimes.com\/es\/events\/oisin-valen-at-beni-ruta-66\/","title":{"rendered":"Oisin &#038; Valen at Beni Ruta 66"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":281661,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[136,203,248],"class_list":{"0":"post-280702","1":"mec-events","2":"type-mec-events","3":"status-publish","4":"has-post-thumbnail","6":"mec_category-beni-ruta-event-list","7":"mec_category-jalon","8":"mec_category-music"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Live Music Jalon Valley- Oisin &amp; Valen at Beni Ruta 66<\/title>\n<meta name=\"description\" content=\"Live Music \/ Musica En Directo \/ Musica En Vivo \/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Live Music Jalon Valley- Oisin &amp; Valen at Beni Ruta 66\" \/>\n<meta property=\"og:description\" content=\"Live Music \/ Musica En Directo \/ Musica En Vivo \/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lasellatimes.com\/es\/events\/oisin-valen-at-beni-ruta-66\/\" \/>\n<meta property=\"og:site_name\" content=\"lasellatimes.com\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-03T09:05:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lasellatimes.com\/wp-content\/uploads\/2026\/03\/oisinvalen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/\",\"name\":\"Live Music Jalon Valley- Oisin & Valen at Beni Ruta 66\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/oisinvalen.jpg\",\"datePublished\":\"2025-09-25T12:32:39+00:00\",\"dateModified\":\"2026-05-03T09:05:57+00:00\",\"description\":\"Live Music \\\/ Musica En Directo \\\/ Musica En Vivo \\\/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/oisinvalen.jpg\",\"contentUrl\":\"https:\\\/\\\/lasellatimes.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/oisinvalen.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/oisin-valen-at-beni-ruta-66\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lasellatimes.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/lasellatimes.com\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Oisin &#038; Valen at Beni Ruta 66\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#website\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/\",\"name\":\"lasellatimes.com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lasellatimes.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#organization\",\"name\":\"lasellatimes.com\",\"url\":\"https:\\\/\\\/lasellatimes.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"lasellatimes.com\"},\"image\":{\"@id\":\"https:\\\/\\\/lasellatimes.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Live Music Jalon Valley- Oisin & Valen at Beni Ruta 66","description":"Live Music \/ Musica En Directo \/ Musica En Vivo \/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Live Music Jalon Valley- Oisin & Valen at Beni Ruta 66","og_description":"Live Music \/ Musica En Directo \/ Musica En Vivo \/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.","og_url":"https:\/\/lasellatimes.com\/es\/events\/oisin-valen-at-beni-ruta-66\/","og_site_name":"lasellatimes.com","article_modified_time":"2026-05-03T09:05:57+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2026\/03\/oisinvalen.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/","url":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/","name":"Live Music Jalon Valley- Oisin & Valen at Beni Ruta 66","isPartOf":{"@id":"https:\/\/lasellatimes.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/#primaryimage"},"image":{"@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/#primaryimage"},"thumbnailUrl":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2026\/03\/oisinvalen.jpg","datePublished":"2025-09-25T12:32:39+00:00","dateModified":"2026-05-03T09:05:57+00:00","description":"Live Music \/ Musica En Directo \/ Musica En Vivo \/ in and around Spains Marina Alta - Denia, Javea, Orba, Pego, Moraira and the Jalon Valley.","breadcrumb":{"@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/#primaryimage","url":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2026\/03\/oisinvalen.jpg","contentUrl":"https:\/\/lasellatimes.com\/wp-content\/uploads\/2026\/03\/oisinvalen.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/lasellatimes.com\/events\/oisin-valen-at-beni-ruta-66\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lasellatimes.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/lasellatimes.com\/events\/"},{"@type":"ListItem","position":3,"name":"Oisin &#038; Valen at Beni Ruta 66"}]},{"@type":"WebSite","@id":"https:\/\/lasellatimes.com\/#website","url":"https:\/\/lasellatimes.com\/","name":"lasellatimes.com","description":"","publisher":{"@id":"https:\/\/lasellatimes.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lasellatimes.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lasellatimes.com\/#organization","name":"lasellatimes.com","url":"https:\/\/lasellatimes.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lasellatimes.com\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"lasellatimes.com"},"image":{"@id":"https:\/\/lasellatimes.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/mec-events\/280702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/comments?post=280702"}],"version-history":[{"count":3,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/mec-events\/280702\/revisions"}],"predecessor-version":[{"id":281719,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/mec-events\/280702\/revisions\/281719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/media\/281661"}],"wp:attachment":[{"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/media?parent=280702"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/tags?post=280702"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/lasellatimes.com\/es\/wp-json\/wp\/v2\/mec_category?post=280702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}